{"id":206,"count":1,"description":"","link":"https:\/\/www.untergeek.de\/de\/tag\/laser-tv\/","name":"Laser-TV","slug":"laser-tv","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Laser-TV Archive - untergeek<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.untergeek.de\/de\/tag\/laser-tv\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laser-TV Archive - untergeek\" \/>\n<meta property=\"og:site_name\" content=\"untergeek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@untergeekDE\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/tag\\\/laser-tv\\\/\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/tag\\\/laser-tv\\\/\",\"name\":\"Laser-TV Archive - untergeek\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/tag\\\/laser-tv\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/tag\\\/laser-tv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.untergeek.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laser-TV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#website\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/\",\"name\":\"untergeek\",\"description\":\"promoting technological serendipity since 1968\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#\\\/schema\\\/person\\\/fa2cb1805e290c4d85f61db3985e73f1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.untergeek.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#\\\/schema\\\/person\\\/fa2cb1805e290c4d85f61db3985e73f1\",\"name\":\"untergeek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"contentUrl\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"width\":64,\"height\":64,\"caption\":\"untergeek\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\"},\"description\":\"Early digital immigrant. Father. Maker. Tinkerer. Serendipist. Journalist. Synth nerd.\",\"sameAs\":[\"http:\\\/\\\/www.untergeek.de\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/untergeekDE\",\"https:\\\/\\\/www.youtube.com\\\/@untergeekDE\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laser-TV Archive - untergeek","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.untergeek.de\/de\/tag\/laser-tv\/","og_locale":"de_DE","og_type":"article","og_title":"Laser-TV Archive - untergeek","og_site_name":"untergeek","twitter_card":"summary_large_image","twitter_site":"@untergeekDE","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.untergeek.de\/tag\/laser-tv\/","url":"https:\/\/www.untergeek.de\/tag\/laser-tv\/","name":"Laser-TV Archive - untergeek","isPartOf":{"@id":"https:\/\/www.untergeek.de\/#website"},"breadcrumb":{"@id":"https:\/\/www.untergeek.de\/tag\/laser-tv\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/www.untergeek.de\/tag\/laser-tv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.untergeek.de\/"},{"@type":"ListItem","position":2,"name":"Laser-TV"}]},{"@type":"WebSite","@id":"https:\/\/www.untergeek.de\/#website","url":"https:\/\/www.untergeek.de\/","name":"untergeek","description":"promoting technological serendipity since 1968","publisher":{"@id":"https:\/\/www.untergeek.de\/#\/schema\/person\/fa2cb1805e290c4d85f61db3985e73f1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.untergeek.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":["Person","Organization"],"@id":"https:\/\/www.untergeek.de\/#\/schema\/person\/fa2cb1805e290c4d85f61db3985e73f1","name":"untergeek","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","contentUrl":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","width":64,"height":64,"caption":"untergeek"},"logo":{"@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png"},"description":"Early digital immigrant. Father. Maker. Tinkerer. Serendipist. Journalist. Synth nerd.","sameAs":["http:\/\/www.untergeek.de","https:\/\/x.com\/https:\/\/twitter.com\/untergeekDE","https:\/\/www.youtube.com\/@untergeekDE"]}]}},"_links":{"self":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/tags\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/posts?tags=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}