{"id":332,"date":"2008-07-09T14:43:42","date_gmt":"2008-07-09T12:43:42","guid":{"rendered":"http:\/\/www.eggers-elektronik.de\/wordpress\/?p=332"},"modified":"2008-07-09T15:04:48","modified_gmt":"2008-07-09T13:04:48","slug":"gemein-sein-zu-mittelstandlern","status":"publish","type":"post","link":"https:\/\/www.untergeek.de\/de\/2008\/07\/gemein-sein-zu-mittelstandlern\/","title":{"rendered":"Gemein sein zu Mittelst\u00e4ndlern!"},"content":{"rendered":"<div class=\"shariff\" data-title=\"Gemein sein zu Mittelst\u00e4ndlern!\" data-info-url=\"http:\/\/ct.de\/-2467514\" data-backend-url=\"https:\/\/www.untergeek.de\/wp-content\/plugins\/shariff-sharing\/backend\/index.php\" data-temp=\"\/tmp\" data-ttl=\"60\" data-service=\"gftr\" data-services='[\"googleplus\",\"facebook\",\"twitter\",\"reddit\",\"info\"]' data-image=\"\" data-url=\"https:\/\/www.untergeek.de\/de\/2008\/07\/gemein-sein-zu-mittelstandlern\/\" data-lang=\"de\" data-theme=\"colored\" data-orientation=\"horizontal\"><\/div><p>Jetzt bin ich mal richtig gemein zur Firma Metz. Zun\u00e4chst einmmal bin ich wild entschlossen, den Sperrfrist-Hinweis auf der Presse-CD einfach zu ignorieren (wenn ich Dinge von dieser CD schon vor dem 18. August ver\u00f6ffentliche: verfolgt mich die 80-j\u00e4hrige Inhaberin Helene Metz dann pers\u00f6nlich?) Nein, auf Metz hacke ich jetzt herum.<\/p>\n<p>Sie machen es einem aber auch zu einfach: angefangen bei der Pressetante, die ihren Einleitungstext von Holz h\u00e4lt &#8211; sprich: ein Papier hat &#8211; und genauso klingt&#8217;s dann auch. \u00dcber den Gesch\u00e4ftsf\u00fchrer, der ausgerechnet Norbert Kotzbauer hei\u00dft und eine ganz altert\u00fcmliche Erfolgsgeschichte erz\u00e4hlt, vom Familienunternehmen, das bis heute &#8222;made in Germany&#8220; verkauft, nicht an die Geizistgeils dieser Welt \u00fcbrigens, mit rund 700 Mitarbeitern und nicht ganz 130 Millionen Umsatz. Und dann statt eines glatten Werbeagentur-Imagetrailers ein handgeschnitztes Videofilmchen mit Statements von sehr, sehr authentisch stolpernden Fernsehfachh\u00e4ndlern.<\/p>\n<p>Verdammt modernes Unternehmen, das.<\/p>\n<p style=\"margin-bottom: 0cm;\">\u201eWarum gibt es eigentlich Metz noch?\u201c, fragt Dr. Kotzbauer zu Beginn und wirkt dabei n\u00e4mlich gar nicht h\u00f6lzern, sondern gibt ein Musterbeispiel gut verhohlenen Selbstbewusstseins. Man kann n\u00e4mlich mit dem Ruf, ein altbackener Qualit\u00e4tshersteller zu sein, sehr gut leben, wenn man zukunftssichere Ger\u00e4te baut.    \t \t \t \t \tUnd einem die Fachzeitschriften das immer wieder bescheinigen. Kotzbauer legt vor: GfK-Studien ergeben, dass Metz einen &#8222;Premium-Aufschlag&#8220; von 120 Prozent verlangen kann &#8211; das hei\u00dft: die Kunden akzeptieren bei diesem Hersteller einen mehr als doppelt so hohen Preis. \u201eDamit k\u00f6nnen wir uns weitgehend aus dem Preiskampf heraushalten\u201c, sagt der Gesch\u00e4ftsf\u00fchrer mit feinem fr\u00e4nkischen Understatement.<\/p>\n<p style=\"margin-bottom: 0cm;\"><em>Und die Neuheiten?<\/em><\/p>\n<p style=\"margin-bottom: 0cm;\">Auch Metz setzt vor allem auf den richtigen Chip. FullHD-Aufl\u00f6sung, also 1920&#215;1080, mit 100Hz und Bildkorrektur, das ist Standard. Ebenso wie der Sensor fr\u00fc die Hintergrundbeleuchtung. Die M\u00f6glichkeit, eine Festplatte nachzur\u00fcsten und dann einen Rekorder schon im Fernseher zu haben, bietet Metz seit Jahren. &#8222;Sirius&#8220; hei\u00dft das Teil. Und es hat einen echten Ausschalter &#8211; keine Standby-Taste. Auch nett: Ger\u00e4te bis zur\u00fcck zum Baujahr 2005 kann man nachtr\u00e4glich auf HDTV-Empfang (digitales Satelliten-Fernsehen nach DVB-S2) nachr\u00fcsten&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jetzt bin ich mal richtig gemein zur Firma Metz. Zun\u00e4chst einmmal bin ich wild entschlossen, den Sperrfrist-Hinweis auf der Presse-CD einfach zu ignorieren (wenn ich Dinge von dieser CD schon vor dem 18. August ver\u00f6ffentliche: verfolgt mich die 80-j\u00e4hrige Inhaberin &hellip; <a href=\"https:\/\/www.untergeek.de\/de\/2008\/07\/gemein-sein-zu-mittelstandlern\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":2,"footnotes":""},"categories":[9,1],"tags":[113,119,120,102],"class_list":["post-332","post","type-post","status-publish","format-standard","hentry","category-maschinelles","category-uncategorized","tag-ifa","tag-metz","tag-mittelstand","tag-preview"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gemein sein zu Mittelst\u00e4ndlern! - untergeek<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.untergeek.de\/de\/2008\/07\/gemein-sein-zu-mittelstandlern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemein sein zu Mittelst\u00e4ndlern! - untergeek\" \/>\n<meta property=\"og:description\" content=\"Jetzt bin ich mal richtig gemein zur Firma Metz. Zun\u00e4chst einmmal bin ich wild entschlossen, den Sperrfrist-Hinweis auf der Presse-CD einfach zu ignorieren (wenn ich Dinge von dieser CD schon vor dem 18. August ver\u00f6ffentliche: verfolgt mich die 80-j\u00e4hrige Inhaberin &hellip; Weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.untergeek.de\/de\/2008\/07\/gemein-sein-zu-mittelstandlern\/\" \/>\n<meta property=\"og:site_name\" content=\"untergeek\" \/>\n<meta property=\"article:published_time\" content=\"2008-07-09T12:43:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2008-07-09T13:04:48+00:00\" \/>\n<meta name=\"author\" content=\"untergeek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/untergeekDE\" \/>\n<meta name=\"twitter:site\" content=\"@untergeekDE\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"untergeek\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/\"},\"author\":{\"name\":\"untergeek\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#\\\/schema\\\/person\\\/fa2cb1805e290c4d85f61db3985e73f1\"},\"headline\":\"Gemein sein zu Mittelst\u00e4ndlern!\",\"datePublished\":\"2008-07-09T12:43:42+00:00\",\"dateModified\":\"2008-07-09T13:04:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/\"},\"wordCount\":347,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#\\\/schema\\\/person\\\/fa2cb1805e290c4d85f61db3985e73f1\"},\"keywords\":[\"IFA\",\"Metz\",\"Mittelstand\",\"Preview\"],\"articleSection\":[\"Maschinelles\",\"Uncategorized\"],\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/\",\"name\":\"Gemein sein zu Mittelst\u00e4ndlern! - untergeek\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#website\"},\"datePublished\":\"2008-07-09T12:43:42+00:00\",\"dateModified\":\"2008-07-09T13:04:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/2008\\\/07\\\/gemein-sein-zu-mittelstandlern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.untergeek.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemein sein zu Mittelst\u00e4ndlern!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#website\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/\",\"name\":\"untergeek\",\"description\":\"promoting technological serendipity since 1968\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#\\\/schema\\\/person\\\/fa2cb1805e290c4d85f61db3985e73f1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.untergeek.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#\\\/schema\\\/person\\\/fa2cb1805e290c4d85f61db3985e73f1\",\"name\":\"untergeek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"contentUrl\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"width\":64,\"height\":64,\"caption\":\"untergeek\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\"},\"description\":\"Early digital immigrant. Father. Maker. Tinkerer. Serendipist. Journalist. Synth nerd.\",\"sameAs\":[\"http:\\\/\\\/www.untergeek.de\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/untergeekDE\",\"https:\\\/\\\/www.youtube.com\\\/@untergeekDE\"],\"url\":\"https:\\\/\\\/www.untergeek.de\\\/de\\\/author\\\/untergeek\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemein sein zu Mittelst\u00e4ndlern! - untergeek","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.untergeek.de\/de\/2008\/07\/gemein-sein-zu-mittelstandlern\/","og_locale":"de_DE","og_type":"article","og_title":"Gemein sein zu Mittelst\u00e4ndlern! - untergeek","og_description":"Jetzt bin ich mal richtig gemein zur Firma Metz. Zun\u00e4chst einmmal bin ich wild entschlossen, den Sperrfrist-Hinweis auf der Presse-CD einfach zu ignorieren (wenn ich Dinge von dieser CD schon vor dem 18. August ver\u00f6ffentliche: verfolgt mich die 80-j\u00e4hrige Inhaberin &hellip; Weiterlesen &rarr;","og_url":"https:\/\/www.untergeek.de\/de\/2008\/07\/gemein-sein-zu-mittelstandlern\/","og_site_name":"untergeek","article_published_time":"2008-07-09T12:43:42+00:00","article_modified_time":"2008-07-09T13:04:48+00:00","author":"untergeek","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/untergeekDE","twitter_site":"@untergeekDE","twitter_misc":{"Verfasst von":"untergeek","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/#article","isPartOf":{"@id":"https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/"},"author":{"name":"untergeek","@id":"https:\/\/www.untergeek.de\/#\/schema\/person\/fa2cb1805e290c4d85f61db3985e73f1"},"headline":"Gemein sein zu Mittelst\u00e4ndlern!","datePublished":"2008-07-09T12:43:42+00:00","dateModified":"2008-07-09T13:04:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/"},"wordCount":347,"commentCount":0,"publisher":{"@id":"https:\/\/www.untergeek.de\/#\/schema\/person\/fa2cb1805e290c4d85f61db3985e73f1"},"keywords":["IFA","Metz","Mittelstand","Preview"],"articleSection":["Maschinelles","Uncategorized"],"inLanguage":"de-DE","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/","url":"https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/","name":"Gemein sein zu Mittelst\u00e4ndlern! - untergeek","isPartOf":{"@id":"https:\/\/www.untergeek.de\/#website"},"datePublished":"2008-07-09T12:43:42+00:00","dateModified":"2008-07-09T13:04:48+00:00","breadcrumb":{"@id":"https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.untergeek.de\/2008\/07\/gemein-sein-zu-mittelstandlern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.untergeek.de\/"},{"@type":"ListItem","position":2,"name":"Gemein sein zu Mittelst\u00e4ndlern!"}]},{"@type":"WebSite","@id":"https:\/\/www.untergeek.de\/#website","url":"https:\/\/www.untergeek.de\/","name":"untergeek","description":"promoting technological serendipity since 1968","publisher":{"@id":"https:\/\/www.untergeek.de\/#\/schema\/person\/fa2cb1805e290c4d85f61db3985e73f1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.untergeek.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":["Person","Organization"],"@id":"https:\/\/www.untergeek.de\/#\/schema\/person\/fa2cb1805e290c4d85f61db3985e73f1","name":"untergeek","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","contentUrl":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","width":64,"height":64,"caption":"untergeek"},"logo":{"@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png"},"description":"Early digital immigrant. Father. Maker. Tinkerer. Serendipist. Journalist. Synth nerd.","sameAs":["http:\/\/www.untergeek.de","https:\/\/x.com\/https:\/\/twitter.com\/untergeekDE","https:\/\/www.youtube.com\/@untergeekDE"],"url":"https:\/\/www.untergeek.de\/de\/author\/untergeek\/"}]}},"_links":{"self":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/posts\/332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/comments?post=332"}],"version-history":[{"count":0,"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/posts\/332\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/media?parent=332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/categories?post=332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/tags?post=332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}