{"id":221,"date":"2008-03-28T09:48:35","date_gmt":"2008-03-28T07:48:35","guid":{"rendered":"http:\/\/www.eggers-elektronik.de\/wordpress\/wp-content\/uploads\/2008\/03\/synaptic.png"},"modified":"2008-03-28T09:48:35","modified_gmt":"2008-03-28T07:48:35","slug":"paketupdate-mit-einem-fehlerfreien-synaptic-und-riesigen-repositories","status":"inherit","type":"attachment","link":"https:\/\/www.untergeek.de\/de\/die-usb-lotpunkte-markiert\/halteklammern-fur-den-neuen-kuhlkorper\/paketupdate-mit-einem-fehlerfreien-synaptic-und-riesigen-repositories\/","title":{"rendered":"Paketupdate mit einem fehlerfreien Synaptic &#8211; und riesigen Repositories."},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-221","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paketupdate mit einem fehlerfreien Synaptic - und riesigen Repositories. - untergeek<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.untergeek.de\/de\/wp-content\/uploads\/2008\/03\/synaptic.png\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:locale:alternate\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paketupdate mit einem fehlerfreien Synaptic - und riesigen Repositories. - untergeek\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.untergeek.de\/de\/die-usb-lotpunkte-markiert\/halteklammern-fur-den-neuen-kuhlkorper\/paketupdate-mit-einem-fehlerfreien-synaptic-und-riesigen-repositories\/\" \/>\n<meta property=\"og:site_name\" content=\"untergeek\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@untergeekDE\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/synaptic.png\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/synaptic.png\",\"name\":\"Paketupdate mit einem fehlerfreien Synaptic - und riesigen Repositories. - untergeek\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#website\"},\"datePublished\":\"2008-03-28T07:48:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/synaptic.png#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/synaptic.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/synaptic.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.untergeek.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die USB-L\u00f6tpunkte (markiert)\",\"item\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/usb-loetpunkte.jpg\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Halteklammern f\u00fcr den neuen K\u00fchlk\u00f6rper&#8230;\",\"item\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2008\\\/03\\\/p1020816.jpg\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Paketupdate mit einem fehlerfreien Synaptic &#8211; und riesigen Repositories.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#website\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/\",\"name\":\"untergeek\",\"description\":\"promoting technological serendipity since 1968\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#\\\/schema\\\/person\\\/fa2cb1805e290c4d85f61db3985e73f1\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.untergeek.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/#\\\/schema\\\/person\\\/fa2cb1805e290c4d85f61db3985e73f1\",\"name\":\"untergeek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"url\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"contentUrl\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\",\"width\":64,\"height\":64,\"caption\":\"untergeek\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.untergeek.de\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/untergeeklet.png\"},\"description\":\"Early digital immigrant. Father. Maker. Tinkerer. Serendipist. Journalist. Synth nerd.\",\"sameAs\":[\"http:\\\/\\\/www.untergeek.de\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/untergeekDE\",\"https:\\\/\\\/www.youtube.com\\\/@untergeekDE\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paketupdate mit einem fehlerfreien Synaptic - und riesigen Repositories. - untergeek","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.untergeek.de\/de\/wp-content\/uploads\/2008\/03\/synaptic.png","og_locale":"de_DE","og_type":"article","og_title":"Paketupdate mit einem fehlerfreien Synaptic - und riesigen Repositories. - untergeek","og_url":"https:\/\/www.untergeek.de\/de\/die-usb-lotpunkte-markiert\/halteklammern-fur-den-neuen-kuhlkorper\/paketupdate-mit-einem-fehlerfreien-synaptic-und-riesigen-repositories\/","og_site_name":"untergeek","og_image":[{"width":800,"height":480,"url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@untergeekDE","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png","url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png","name":"Paketupdate mit einem fehlerfreien Synaptic - und riesigen Repositories. - untergeek","isPartOf":{"@id":"https:\/\/www.untergeek.de\/#website"},"datePublished":"2008-03-28T07:48:35+00:00","breadcrumb":{"@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.untergeek.de\/"},{"@type":"ListItem","position":2,"name":"Die USB-L\u00f6tpunkte (markiert)","item":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/usb-loetpunkte.jpg"},{"@type":"ListItem","position":3,"name":"Halteklammern f\u00fcr den neuen K\u00fchlk\u00f6rper&#8230;","item":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/p1020816.jpg"},{"@type":"ListItem","position":4,"name":"Paketupdate mit einem fehlerfreien Synaptic &#8211; und riesigen Repositories."}]},{"@type":"WebSite","@id":"https:\/\/www.untergeek.de\/#website","url":"https:\/\/www.untergeek.de\/","name":"untergeek","description":"promoting technological serendipity since 1968","publisher":{"@id":"https:\/\/www.untergeek.de\/#\/schema\/person\/fa2cb1805e290c4d85f61db3985e73f1"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.untergeek.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":["Person","Organization"],"@id":"https:\/\/www.untergeek.de\/#\/schema\/person\/fa2cb1805e290c4d85f61db3985e73f1","name":"untergeek","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","contentUrl":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png","width":64,"height":64,"caption":"untergeek"},"logo":{"@id":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2018\/11\/untergeeklet.png"},"description":"Early digital immigrant. Father. Maker. Tinkerer. Serendipist. Journalist. Synth nerd.","sameAs":["http:\/\/www.untergeek.de","https:\/\/x.com\/https:\/\/twitter.com\/untergeekDE","https:\/\/www.youtube.com\/@untergeekDE"]}]}},"description":{"rendered":"<div class=\"shariff\" data-title=\"Paketupdate mit einem fehlerfreien Synaptic &#8211; und riesigen Repositories.\" data-info-url=\"http:\/\/ct.de\/-2467514\" data-backend-url=\"https:\/\/www.untergeek.de\/wp-content\/plugins\/shariff-sharing\/backend\/index.php\" data-temp=\"\/tmp\" data-ttl=\"60\" data-service=\"gftr\" data-services='[\"googleplus\",\"facebook\",\"twitter\",\"reddit\",\"info\"]' data-image=\"\" data-url=\"https:\/\/www.untergeek.de\/de\/die-usb-lotpunkte-markiert\/halteklammern-fur-den-neuen-kuhlkorper\/paketupdate-mit-einem-fehlerfreien-synaptic-und-riesigen-repositories\/\" data-lang=\"de\" data-theme=\"colored\" data-orientation=\"horizontal\"><\/div><p class=\"attachment\"><a href='https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png'><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"120\" src=\"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic-300x180.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic-300x180.png 300w, https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png 800w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":800,"height":480,"hwstring_small":"height='76' width='128'","file":"\/mnt\/web7\/42\/79\/519379\/htdocs\/wordpress\/wp-content\/uploads\/2008\/03\/synaptic.png","sizes":{"thumbnail":{"file":"synaptic-150x150.png","width":150,"height":150,"source_url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic-150x150.png"},"medium":{"file":"synaptic-300x180.png","width":300,"height":180,"source_url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic-300x180.png"},"full":{"file":"synaptic.png","width":800,"height":480,"mime_type":"image\/png","source_url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":214,"source_url":"https:\/\/www.untergeek.de\/wp-content\/uploads\/2008\/03\/synaptic.png","_links":{"self":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/media\/221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/comments?post=221"}],"wp:attached-to":[{"embeddable":true,"post_type":"attachment","id":214,"href":"https:\/\/www.untergeek.de\/de\/wp-json\/wp\/v2\/media\/214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}